{"id":717,"date":"2019-07-01T15:59:29","date_gmt":"2019-07-01T20:59:29","guid":{"rendered":"https:\/\/maratonesyviajes.com\/viajes\/?p=717"},"modified":"2019-07-01T15:59:31","modified_gmt":"2019-07-01T20:59:31","slug":"rutas-por-polonia","status":"publish","type":"post","link":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/","title":{"rendered":"Rutas por Polonia"},"content":{"rendered":"<h6 class=\"collapseomatic \" id=\"id6a56d05b32ee1\"  tabindex=\"0\" title=\"Todas las Capitales Imperiales y Polonia\"    >Todas las Capitales Imperiales y Polonia<\/h6><div id=\"target-id6a56d05b32ee1\" class=\"collapseomatic_content \">\n\n\n\n<p><strong>D\u00eda 01 (Lunes) Berl\u00edn<\/strong><\/p>\n\n\n\n<p><strong><em>Llegamos a Europa <\/em><\/strong><\/p>\n\n\n\n<p>Llegada&nbsp; al\naeropuerto y <strong>traslado<\/strong> al hotel<strong>.&nbsp; &nbsp;&nbsp;Alojamiento.\n<\/strong>A las 19.30&nbsp; hrs, tendr\u00e1 lugar la reuni\u00f3n con el gu\u00eda en\nla recepci\u00f3n del hotel donde conoceremos&nbsp;\nal resto de participantes<\/p>\n\n\n\n<p><strong>D\u00eda 02 (Martes) Berl\u00edn.<\/strong><\/p>\n\n\n\n<p><strong><em>&#8230;Capital liberada y libre<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno y visita panor\u00e1mica<\/strong> con&nbsp; la Puerta\nde Brandemburgo,&nbsp; el Reichstag; la Unter\nden Linten, Iglesia conmemorativa del K\u00e1iser en la Ku\u00b4Damm,&nbsp; Alexander Platz,&nbsp; East&nbsp;\nSide Gallery, memorial al Muro de Berl\u00edn. Posibilidad de visitar\nopcionalmente alguno de los Museos de Berl\u00edn y el Campo Concentraci\u00f3n de\nSchasenhausen.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p>ERIAL24 D\u00cdAS \/ 9 PA\u00cdSES)<\/p>\n\n\n\n<p><strong>D\u00eda 03 (Mi\u00e9rcoles) Berl\u00edn \u2013 Poznan \u2013\nVarsovia<\/strong><\/p>\n\n\n\n<p><strong><em>.. Por fin \u2026 Polonia <\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>Salida con\ndirecci\u00f3n <strong>Poznan<\/strong>. Llegada y tour de orientaci\u00f3n de una de las mas\nantiguas y grandes ciudades de Polonia. El centro tur\u00edstico de la ciudad es la\nAntigua Plaza del Mercado con valiosos monumentos y numerosos museos. El\nayuntamiento renacentista, con bellas galer\u00edas abiertas, alberga el Museo de\nHistoria de la Ciudad, etc. Continuaci\u00f3n del viaje hasta Varsovia. &nbsp;<strong>&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 04 (Jueves) \u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>La gran capital<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno.\nVisita panor\u00e1mica <\/strong>de la ciudad que nos mostrar\u00e1 los principales monumentos\ny cualidades de s\u00ed misma, especialmente aquellos situados alrededor de la ruta\nreal, ayuntamiento y los distintos homenajes a sucesos recientes de la segunda\nguerra mundial como el gueto jud\u00edo.Tarde libre para realizar algunavisita\nfacultativa: Castillo Real o Palacio Wilanow. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 05 (Viernes) \u2013 Varsovia \u2013 Czestochowa\n\u2013 Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>Santuarios y tradiciones<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salimos al\nencuentro de la Virgen Morena de todos los polacos. Su santuario nos\nsobrecoger\u00e1 por su iluminaci\u00f3n y estructura. Son millones los visitantes que\ndurante siglo ha atra\u00eddo esta Virgen. La devoci\u00f3n mariana es la reina en <strong>Czestochowa<\/strong>.\nContinuaremos hacia Cracovia . El castillo de Cracovia, las iglesias\nmedievales, la ciudad vieja, son algunos de los monumentos que nos\nimpresionar\u00e1n. La Lonja hist\u00f3rica, a\u00fan mercadillo tradicional, el gueto jud\u00edo y\nlas calles de los palacios barrocos ser\u00e1n otras de las gemas que se nos\nmostrar\u00e1n en la <strong>visita panor\u00e1mica <\/strong>de la ciudad. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 06 (S\u00e1bado) Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>La Catedral de Sal<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>D\u00eda libre para\nvisitar opcionalmente el Campo de Concentraci\u00f3n de\nAuschwith y las Minas de sal de Wielivska. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 07 (Domingo) Cracovia &#8211; Budapest<\/strong><\/p>\n\n\n\n<p><strong><em>K.u.K.\n\u2026 Imperial y real \u2026<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida a\nBudapest, atravesando los Montes Tatras y pasando por la localidad de Banska\nBystrica. Por la tarde llegada a Budapest, capital h\u00fangara conocida como la\nReina del Danubio. Es la ciudad de los ba\u00f1os, de la danza, de la m\u00fasica, de los\nlegendarios salones de t\u00e9-pasteler\u00edas y de los caf\u00e9s literarios. Es tambi\u00e9n el\nescaparate del modernismo, que conoci\u00f3 su \u00e9poca dorada a finales del s. XIX.\nImposible resistirse a tantos atractivos!!. <strong>Visita panor\u00e1mica <\/strong>en la que\nrecorreremos las zonas de Buda y la de Pest, el Basti\u00f3n de los Pescadores, la\nPlaza de los H\u00e9roes, la Avenida Andrassy, etc. <strong>Alojamiento<\/strong>. <\/p>\n\n\n\n<p><strong>D\u00eda 08 (Lunes)&nbsp; Budapest<\/strong><\/p>\n\n\n\n<p><strong><em>Crisol\nreligioso<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>&nbsp;D\u00eda\nlibre en el que les propondremos realizar opcionalmente una visita a la llamada\nBudapest art\u00edstica con entrada y visita al Parlamento y Bas\u00edlica de S. Esteban.<strong>&nbsp; Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 09 (Martes)\nBudapest &#8211; Praga<\/strong><\/p>\n\n\n\n<p><strong><em>Nos vamos de Hungr\u00eda<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salida hacia la\nRepublica Checa y su capital Praga. Llegada por la tarde y primer contacto con\nlas calles y gentes de la m\u00e1s encantadora ciudad de Centro Europa. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 10 (Mi\u00e9rcoles) Praga<\/strong><\/p>\n\n\n\n<p><strong><em>Bienvenidos a la Rep\u00fablica\nCheca<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong><strong>Visita\npanor\u00e1mica<\/strong> con la Torre de la\nP\u00f3lvora, la Plaza de San Wenceslao, la Plaza de la Ciudad Vieja, el\nAyuntamiento con su torre y el famos\u00edsimo reloj astron\u00f3mico, barrio Jud\u00edo y\nPuente de Carlos. Tarde libre. <strong>&nbsp;<\/strong>&nbsp;<strong>&nbsp;<\/strong>&nbsp;&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 11 (Jueves) Praga<\/strong><\/p>\n\n\n\n<p><strong><em>Plenitud <\/em><\/strong><strong><em>de vida y arte<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. D\u00eda libre donde se ofrecer\u00e1 visitar opcionalmente la\nPraga Art\u00edstica : Barrio del Castillo y Callej\u00f3n de Oro<strong>.&nbsp; <\/strong>&nbsp;<strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 12 (Viernes) Praga \u2013\nBratislava \u2013 Viena<\/strong><\/p>\n\n\n\n<p><strong><em>Ciudades Imperiales<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salida hacia <strong>Bratislava<\/strong>, llegada y <strong>tour de\norientaci\u00f3n <\/strong>.Continuaci\u00f3n a Viena, llegada y <strong>visita panor\u00e1mica<\/strong>\nrecorriendo la Avenida del Ring con la Opera, el Museo de Bellas Artes, el\nParlamento, el Ayuntamiento, la Universidad, la Bolsa, la Iglesia Votiva,\nPalacio Belvedere, etc. pasando tambi\u00e9n por el Prater para hacer una foto a su\nfamosa Noria. La visita finaliza con un <strong>paseo incluido<\/strong> por el centro\nhist\u00f3rico peatonal de Viena que nos llevar\u00e1 hasta la Catedral de San Esteban. <strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 13 (S\u00e1bado) Viena<\/strong><\/p>\n\n\n\n<p><strong><em>Danubio Azul y vino verde<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>D\u00eda libre para visitar opcionalmente la llamada \u201cViena\nart\u00edstica\u201d. <strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 14 (Domingo)\nViena &#8211; ciudad de origen&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n\n\n\n<p><strong><em>Vuelta a casa<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y tiempo libre hasta la hora del <strong>traslado<\/strong> al aeropuerto. Fin de nuestros servicios.<\/p>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"text-align:center\"><strong>PDF<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.surland.com\/uploads\/es\/128-129-045015.pdf\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=50%2C50&#038;ssl=1\" alt=\"\" class=\"wp-image-538\" width=\"50\" height=\"50\" srcset=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n<\/div>\n\n\n<h6 class=\"collapseomatic \" id=\"id6a56d05b32f7c\"  tabindex=\"0\" title=\"Par\u00eds, Pa\u00edses Bajos y Polonia\"    >Par\u00eds, Pa\u00edses Bajos y Polonia<\/h6><div id=\"target-id6a56d05b32f7c\" class=\"collapseomatic_content \">\n\n\n\n<p><strong>D\u00eda 01 (Domingo) Par\u00eds.<\/strong><\/p>\n\n\n\n<p><strong><em>Llegamos a Europa<\/em><\/strong><\/p>\n\n\n\n<p>Llegada&nbsp; al aeropuerto y <strong>traslado<\/strong> al hotel. <strong>Alojamiento.\n<\/strong>A las 19.30&nbsp; hrs, tendr\u00e1 lugar la reuni\u00f3n con el gu\u00eda en\nla recepci\u00f3n del hotel donde conoceremos&nbsp;\nal resto de participantes. Por la noche, efectuaremos la <strong>visita incluida<\/strong> de Par\u00eds iluminado.\n<\/p>\n\n\n\n<p><strong>D\u00eda\n02 (Lunes) Par\u00eds<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>La ciudad Luz<strong><\/strong><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. <strong>Visita\npanor\u00e1mica<\/strong> con&nbsp; Campos El\u00edseos, Plaza\nde la Concorde, Arco del Triunfo, Opera, Barrio Latino,&nbsp; Sorbona, Pante\u00f3n, Inv\u00e1lidos, Escuela Militar,\nCampo de Marte, etc. Resto del d\u00eda libre. <strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 03 (Martes) Par\u00eds<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>Boutiques\ny champagne<\/em><\/strong><\/p>\n\n\n\n<p><strong>De<\/strong><strong>sayuno<\/strong>.\nD\u00eda libre para disfrutar opcionalmente de los jardines y palacio de Versalles. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 04 (Mi\u00e9rcoles) Par\u00eds\n&#8211; Bruselas<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>Rumbo a&nbsp; Flandes<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida a Bruselas<strong> Visita panor\u00e1mica<\/strong> con la\nGrand Place, el Atomium, Catedral de San Miguel, etc.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 05 (Jueves) Bruselas\n\u2013&nbsp; Gante \u2013 Brujas<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>De Carlos V a los rom\u00e1nticos canales<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salida a <strong>Gante y visita panor\u00e1mica. <\/strong>Continuaci\u00f3n\na <strong>Brujas<\/strong>, ciudad que conserva su belleza medieval y <strong>visita panor\u00e1mica<\/strong>.&nbsp;<strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 06 (Viernes) Brujas\n\u2013 Rotterdam &#8211; Delf &#8211; La Haya \u2013 \u00c1msterdam<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>Venciendo al mar<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida direcci\u00f3n Amsterdam con breves paradas en\nRotterdam,&nbsp; Delf y La Haya.&nbsp; Llegada y <strong>&nbsp;alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 07 (S\u00e1bado) \u00c1msterdam.<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>Diamantes,\ntulipanes.<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>.&nbsp; <strong>Visita\npanor\u00e1mica<\/strong>&nbsp; con parada en el molino\nde Rembrandt. Proseguimos con el Barrio Sur, Plaza de los museos, Gran Canal Amstel,\nAntiguo Puerto, Plaza Damm etc. con <strong>paseo\nincluido <\/strong>por el centro hist\u00f3rico. Tambi\u00e9n dispondremos de tiempo libre para\nvisitar opcionalmente Marken y Volendam as\u00ed como el Barrio Rojo y Canales.<strong> Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 08 (Domingo) \u00c1msterdam \u2013 Boppard &#8211; Crucero Rhin \u2013 St. Goar \u2013\nFrankfurt<\/strong><\/p>\n\n\n\n<p><strong><em>Un encantador paseo<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salida siguiendo el curso del Rhin para llegar a\nBoppard, donde embarcaremos en un crucero que nos permitir\u00e1 ver la Roca de\nLoreley y multitud de castillos y vi\u00f1edos en las laderas del rio Rhin.\nDesembarcamos en St. Goar donde tendremos tiempo para pasear. Continuaremos\nnuestro viaje hasta la <strong>Plaza Rommer<\/strong> en Frankfurt para visitarla. <strong>&nbsp;&nbsp;Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 09 (Lunes) Frankfurt\n\u2013 Erfurt -Berl\u00edn<\/strong><\/p>\n\n\n\n<p><strong><em>Espiritualidad\ny Humanismo<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida hacia <strong>Erfurt<\/strong> donde efectuaremos un <strong>tour\nde orientaci\u00f3n<\/strong> de esta ciudad medieval, en la encrucijada de dos\ngrandes rutas del Imperio que comunicaban la regi\u00f3n del Rhin con Rusia y\ndonde&nbsp; el joven Lutero estudi\u00f3 filosof\u00eda\n. Cuna del Humanismo germano. Continuaci\u00f3n hasta Berl\u00edn.&nbsp; <strong>&nbsp;&nbsp;Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 10 (Martes)Berl\u00edn.<\/strong><\/p>\n\n\n\n<p><strong><em>&#8230;Capital liberada y libre<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno y visita panor\u00e1mica<\/strong> con&nbsp; la Puerta\nde Brandemburgo,&nbsp; el Reichstag; la Unter\nden Linten, Iglesia conmemorativa del K\u00e1iser en la Ku\u00b4Damm,&nbsp; Alexander Platz,&nbsp; East&nbsp;\nSide Gallery, memorial al Muro de Berl\u00edn.&nbsp; Posibilidad de visitar opcionalmente alguno\nde los Museos de Berl\u00edn y el Campo de Concentraci\u00f3n de Schasenhausen.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>Dia 11 (Mi\u00e9rcoles) Berl\u00edn \u2013 Poznan \u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>.. Por\nfin \u2026 Polonia <\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>Salida con direcci\u00f3n\n<strong>Poznan<\/strong>. Llegada y <strong>tour de\norientaci\u00f3n<\/strong> de una de las mas antiguas y grandes ciudades de Polonia.\nContinuaci\u00f3n del viaje hasta Varsovia. <strong>&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 12 (Jueves) \u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>La\ngran capital<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>La<strong> visita panor\u00e1mica <\/strong>nos mostrar\u00e1 los principales monumentos y\ncualidades de s\u00ed misma, especialmente aquellos situados alrededor de la ruta\nreal, ayuntamiento y los distintos homenajes a sucesos de la segunda guerra\nmundial.Tarde libre. <strong>&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 13 (Viernes) \u2013 Varsovia \u2013 Czestochowa\n\u2013 Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>Santuarios\ny tradiciones<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salimos al\nencuentro de la Virgen Morena de todos los polacos. Su santuario nos\nsobrecoger\u00e1 por su iluminaci\u00f3n y estructura. La devoci\u00f3n mariana es la reina en\n<strong>Czestochowa<\/strong>. Continuaremos hacia Cracovia . El castillo de Cracovia, las\niglesias medievales, la ciudad vieja son algunos de los monumentos que nos\nimpresionar\u00e1n en la <strong>visita panor\u00e1mica <\/strong>de la ciudad. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 14 (S\u00e1bado) Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>La\nCatedral de Sal<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>D\u00eda libre para\nvisitar opcionalmente el Campo de Concentraci\u00f3n de\nAuschwith y las Minas de sal de Wielivska. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 15 (Domingo) Cracovia &#8211; Budapest<\/strong><\/p>\n\n\n\n<p><strong><em>K.u.K.\n\u2026 Imperial y real \u2026<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida a\nBudapest, atravesando los Montes Tatras y pasando por Banska Bystrica. Por la\ntarde llegada a Budapest y <strong>visita panor\u00e1mica <\/strong>en la que recorreremos las\nzonas de Buda y la de Pest, el Basti\u00f3n de los Pescadores, la Plaza de los\nH\u00e9roes, la Avenida Andrassy, etc. <strong>&nbsp;&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>. <\/p>\n\n\n\n<p><strong>D\u00eda 16 (Lunes)&nbsp; Budapest<\/strong><\/p>\n\n\n\n<p><strong><em>Crisol\nreligioso<\/em><\/strong><\/p>\n\n\n\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Desayuno.\n<\/strong>&nbsp;D\u00eda libre en el que les propondremos realizar\nopcionalmente una visita a la llamada Budapest art\u00edstica <strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 17 (Martes)\nBudapest &#8211; ciudad de origen&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n\n\n\n<p><strong><em>Vuelta\na casa<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y tiempo libre hasta la hora del <strong>traslado<\/strong> al aeropuerto. Fin de nuestros servicios.<\/p>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"text-align:center\"><strong>PDF<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.surland.com\/uploads\/es\/134-135-045106.pdf\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=50%2C50&#038;ssl=1\" alt=\"\" class=\"wp-image-538\" width=\"50\" height=\"50\" srcset=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n<\/div>\n\n\n<h6 class=\"collapseomatic \" id=\"id6a56d05b32fbe\"  tabindex=\"0\" title=\"Par\u00eds, Berlin y Polonia\"    >Par\u00eds, Berlin y Polonia<\/h6><div id=\"target-id6a56d05b32fbe\" class=\"collapseomatic_content \">\n\n\n\n<p><strong>D\u00eda\n01 (Jueves) Par\u00eds<\/strong><\/p>\n\n\n\n<p><strong><em>Llegamos a Europa <\/em><\/strong><\/p>\n\n\n\n<p>Llegada&nbsp; al\naeropuerto y <strong>traslado<\/strong> al hotel. <strong>Alojamiento.&nbsp; <\/strong>A\nlas 19.30&nbsp; hrs, tendr\u00e1 lugar la reuni\u00f3n\ncon el gu\u00eda en la recepci\u00f3n del hotel donde conoceremos&nbsp; al resto de participantes. &nbsp;Por la noche paseo nocturno <strong>incluido<\/strong> por Par\u00eds iluminado.<\/p>\n\n\n\n<p><strong>D\u00eda 02 (Viernes) Par\u00eds<\/strong><\/p>\n\n\n\n<p><strong><em>La ciudad Luz<\/em><\/strong><em> <\/em><\/p>\n\n\n\n<p><strong>Desayuno.\nVisita panor\u00e1mica<\/strong><strong> con Campos El\u00edseos, Plaza de la Concorde, Arco del Triunfo, Opera,\nBarrio Latino,&nbsp; Sorbona, Pante\u00f3n,\nInv\u00e1lidos, Escuela Militar, Campo de Marte, etc. Tarde libre para disfrutar\nopcionalmente del Palacio y Jardines de Versalles<\/strong><strong> <\/strong><strong>Alojamiento<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 03 (S\u00e1bado) Par\u00eds.<\/strong><\/p>\n\n\n\n<p><strong><em>Oohhh, la , la<\/em><\/strong><\/p>\n\n\n\n<p><strong>De<\/strong><strong>sayuno<\/strong>. D\u00eda libre <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 04 (Domingo) Par\u00eds &#8211; Boppard &#8211; Crucero por\nel Rhin&nbsp; &#8211; St. Goar &#8211; Frankfurt.<\/strong><\/p>\n\n\n\n<p><strong><em>Un encantador paseo<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>Salida a Boppard. Embarcaremos en un <strong>crucero<\/strong> que nos permitir\u00e1 ver la Roca de Loreley y multitud de\ncastillos y vi\u00f1edos en las laderas del Rhin. Desembarcamos en St. Goar y\ncontinuaremos el viaje hasta la <strong>Plaza\nRommer<\/strong> en Frankfurt para visitarla<strong>. &nbsp;&nbsp;Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda\n05 (Lunes) Frankfurt \u2013 Erfurt -Berl\u00edn<\/strong><\/p>\n\n\n\n<p><strong><em>Espiritualidad y\nHumanismo<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida hacia <strong>Erfurt<\/strong> y&nbsp;\n<strong>tour de orientaci\u00f3n<\/strong> de esta ciudad medieval, cuna del Humanismo\ngermano. Continuaci\u00f3n a Berl\u00edn.&nbsp; <strong>&nbsp;&nbsp;Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda\n06 (Martes) Berl\u00edn.<\/strong><\/p>\n\n\n\n<p><strong><em>&#8230;Capital liberada y\nlibre<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno y visita panor\u00e1mica<\/strong> con&nbsp; la Puerta\nde Brandemburgo,&nbsp; el Reichstag; la Unter\nden Linten, Iglesia conmemorativa del K\u00e1iser en la Ku\u00b4Damm,&nbsp; Alexander Platz,&nbsp; East&nbsp;\nSide Gallery, memorial al Muro de Berl\u00edn. <strong>&nbsp;&nbsp;<\/strong>Posibilidad de visitar opcionalmente\nalguno de los Museos de Berl\u00edn y el Campo Concentraci\u00f3n de Schasenhausen.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p>IAL24 D\u00cdAS \/ 9 PA\u00cdSES)<\/p>\n\n\n\n<p><strong>D\u00eda 07\n(Mi\u00e9rcoles) Berl\u00edn \u2013 Poznan \u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>.. Por fin \u2026 Polonia <\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno.\n<\/strong>Salida con direcci\u00f3n <strong>Poznan<\/strong>. Llegada y\ntour de orientaci\u00f3n de una de las mas antiguas y grandes ciudades de Polonia.\nEl centro tur\u00edstico de la ciudad es la Antigua Plaza del Mercado con valiosos\nmonumentos y numerosos museos. El ayuntamiento renacentista, con bellas\ngaler\u00edas abiertas, alberga el Museo de Historia de la Ciudad, etc. Continuaci\u00f3n\ndel viaje hasta Varsovia. &nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 08 (Jueves)\n\u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>La gran capital<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno.\nVisita panor\u00e1mica <\/strong>de la ciudad que nos mostrar\u00e1 los principales\nmonumentos y cualidades de s\u00ed misma, especialmente aquellos situados alrededor\nde la ruta real, ayuntamiento y los distintos homenajes a sucesos recientes de\nla segunda guerra mundial como el gueto jud\u00edo.Tarde libre para realizar\nalgunavisita facultativa: Castillo Real o Palacio Wilanow <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 09 (Viernes)\n\u2013 Varsovia \u2013 Czestochowa \u2013 Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>Santuarios y tradiciones<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>.\nSalimos al encuentro de la Virgen Morena de todos los polacos. Su santuario nos\nsobrecoger\u00e1 por su iluminaci\u00f3n y estructura. Son millones los visitantes que\ndurante siglo ha atra\u00eddo esta Virgen. La devoci\u00f3n mariana es la reina en <strong>Czestochowa<\/strong>.\nContinuaremos hacia Cracovia . El castillo de Cracovia, las iglesias\nmedievales, la ciudad vieja, son algunos de los monumentos a visitar. La Lonja\nhist\u00f3rica, a\u00fan mercadillo tradicional, el gueto jud\u00edo y las calles de los\npalacios barrocos ser\u00e1n otras de las gemas que se nos mostrar\u00e1n en la <strong>visita\npanor\u00e1mica <\/strong>de la ciudad. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 10 (S\u00e1bado)\nCracovia<\/strong><\/p>\n\n\n\n<p><strong><em>La Catedral de Sal<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>D\u00eda libre para\nvisitar opcionalmente el Campo de Concentraci\u00f3n de\nAuschwith y las Minas de sal de Wielivska. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda\n11 (Domingo) Cracovia &#8211; ciudad de origen<\/strong><\/p>\n\n\n\n<p><strong><em>Vuelta a casa<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y tiempo libre hasta la hora del <strong>traslado<\/strong> al aeropuerto. Fin de nuestros servicios.<\/p>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"text-align:center\"><strong>PDF<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.surland.com\/uploads\/es\/138-139-045220.pdf\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=48%2C48&#038;ssl=1\" alt=\"\" class=\"wp-image-538\" width=\"48\" height=\"48\" srcset=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n<\/div>\n\n\n<h6 class=\"collapseomatic \" id=\"id6a56d05b32ffb\"  tabindex=\"0\" title=\"Centroeuropa e Italia\"    >Centroeuropa e Italia<\/h6><div id=\"target-id6a56d05b32ffb\" class=\"collapseomatic_content \">\n\n\n\n<p><strong>D\u00eda 01 (Lunes) Berl\u00edn<\/strong><\/p>\n\n\n\n<p><strong><em>Llegamos a Europa <\/em><\/strong><\/p>\n\n\n\n<p>Llegada&nbsp; al\naeropuerto y <strong>traslado<\/strong> al hotel<strong>.&nbsp;&nbsp;&nbsp; Alojamiento.\n<\/strong>A las 19.30&nbsp; hrs, tendr\u00e1 lugar la reuni\u00f3n con el gu\u00eda en\nla recepci\u00f3n del hotel <\/p>\n\n\n\n<p><strong>D\u00eda 02 (Martes) Berl\u00edn.<\/strong><\/p>\n\n\n\n<p><strong><em>&#8230;Capital liberada y libre<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno y visita panor\u00e1mica<\/strong> con&nbsp; la Puerta\nde Brandemburgo,&nbsp; el Reichstag; la Unter\nden Linten, Iglesia conmemorativa del K\u00e1iser en la Ku\u00b4Damm,&nbsp; Alexander Platz,&nbsp; East&nbsp;\nSide Gallery, memorial al Muro de Berl\u00edn. Vistia opcional de alguno de\nlos Museos de Berl\u00edn y el Campo Concentraci\u00f3n de Schasenhausen.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p>ERIAL24 D\u00cdAS \/ 9 PA\u00cdSES)<\/p>\n\n\n\n<p><strong>D\u00eda 03 (Mi\u00e9rcoles) Berl\u00edn \u2013 Poznan \u2013\nVarsovia<\/strong><\/p>\n\n\n\n<p><strong><em>.. Por fin \u2026 Polonia <\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>Salida a <strong>Poznan<\/strong>\ny <strong>tour de orientaci\u00f3n<\/strong> de una de las\nmas antiguas y grandes ciudades de Polonia.&nbsp;\nContinuaci\u00f3n hasta Varsovia.&nbsp; <strong>&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 04 (Jueves) \u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>La gran capital<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno.\nVisita panor\u00e1mica <\/strong>que nos mostrar\u00e1 los principales monumentos y cualidades\nde s\u00ed misma. Tarde libre . <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 05 (Viernes) \u2013 Varsovia \u2013 Czestochowa\n\u2013 Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>Santuarios y tradiciones<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Salimos al\nencuentro de la Virgen Morena de todos los polacos, la devoci\u00f3n mariana es la\nreina en <strong>Czestochowa<\/strong>. Continuaremos hacia Cracovia y <strong>visita\npanor\u00e1mica <\/strong>con el castillo, las iglesias medievales, la ciudad vieja,&nbsp; gueto jud\u00edo etc. &nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 06 (S\u00e1bado) Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>La Catedral de Sal<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>&nbsp;Visita opcional del Campo de Concentraci\u00f3n de Auschwith y las Minas de sal de Wielivska. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 07 (Domingo) Cracovia &#8211; Budapest<\/strong><\/p>\n\n\n\n<p><strong><em>K.u.K.\n\u2026 Imperial y real \u2026<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y salida a\nBudapest. <strong>Visita panor\u00e1mica <\/strong>en la que recorreremos las zonas de Buda y\nla de Pest, el Basti\u00f3n de los Pescadores, la Plaza de los H\u00e9roes, la Avenida\nAndrassy, etc. <strong>&nbsp;&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>. <\/p>\n\n\n\n<p><strong>D\u00eda 08 (Lunes)&nbsp; Budapest<\/strong><\/p>\n\n\n\n<p><strong><em>Crisol\nreligioso<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>&nbsp;Vistia\nopcional de la llamada Budapest art\u00edstica con entrada y visita al Parlamento y\nBas\u00edlica de S. Esteban.<strong> &nbsp;Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda 09 (Martes)\nBudapest &#8211; Venecia&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cruzando Eslovenia<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> . Salida en una\nlarga etapa de autocar que nos llevar\u00e1 atravesando&nbsp; Eslovenia hasta Venecia. <strong>Alojamiento<\/strong><\/p>\n\n\n\n<p><strong>D\u00eda\n10 (Mi\u00e9rcoles) Venecia \u2013 Pisa &#8211; Florencia<\/strong><\/p>\n\n\n\n<p><strong><em>Del carnaval al Renacimiento<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. Tomaremos un <strong>barco<\/strong>&nbsp;hasta la Plaza de San Marcos donde\nharemos un <strong>tour de orientaci\u00f3n<\/strong> destacando la Bas\u00edlica, el Campanile, el\nPalacio Ducal etc, con posibilidad de visitar un horno donde nos har\u00e1n una\ndemostraci\u00f3n del arte del cristal de Murano.&nbsp; Opcionalmente paseo en\nG\u00f3ndola. Despu\u00e9s, salida hacia Pisa y tiempo libre para conocer su famosa Torre\nInclinada en la Plaza de los Milagros. Llegada final a Florencia. <strong>Alojamiento<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>D\u00eda\n11 (Jueves) Florencia &#8211; Roma<\/strong><\/p>\n\n\n\n<p><strong><em>Toscana y Lazio<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno <\/strong>y&nbsp; y <strong>visita panor\u00e1mica a pie<\/strong>\ncon la Plaza de la Signoria, el Duomo, la impresionante Santa Mar\u00eda dei Fiore,\nel Battisterio, la Santa Croce, el Ponte Vecchio, etc. Por la tarde\ncontinuaci\u00f3n a Roma. Llegada y visita opcional a la Roma Barroca.&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda\n12 (Viernes) Roma.<\/strong><\/p>\n\n\n\n<p><strong><em>La\neterna, la imperial, la cristiana<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. <strong>Visita panor\u00e1mica<\/strong> recorriendo\nel Lungotevere, Porta Ostiense, Termas de Caracalla, St. Mar\u00eda la Mayor, San\nJuan de Letr\u00e1n, Coliseo, Foros Imperiales, Plaza Venecia, Teatro Marcello,\nCirco Massimo, Boca de la Verdad, etc <strong>Paseo incluido<\/strong> al barrio del\nTrastevere.&nbsp; Posibilidad de visitar\nopcionalmente los Museos Vaticanos<strong> . Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda\n13 (S\u00e1bado) Roma (N\u00e1poles &#8211; Capri).<\/strong><\/p>\n\n\n\n<p><strong><em>Vesubio\ny pizza<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>. D\u00eda libre para visitar opcionalmente&nbsp;\n<strong>N\u00e1poles y Capri<\/strong>.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda\n14 (Domingo)&nbsp; Roma&nbsp; \u2013 ciudad de origen<\/strong><\/p>\n\n\n\n<p><strong><em>Vuelta a casa<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y tiempo libre hasta la hora del <strong>traslado<\/strong> al aeropuerto. Fin de nuestros servicios<\/p>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"text-align:center\"><strong>PDF<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.surland.com\/uploads\/es\/140-141-045338.pdf\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=48%2C48&#038;ssl=1\" alt=\"\" class=\"wp-image-538\" width=\"48\" height=\"48\" srcset=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n<\/div>\n\n\n<h6 class=\"collapseomatic \" id=\"id6a56d05b33031\"  tabindex=\"0\" title=\"Berlin y Polonia\"    >Berlin y Polonia<\/h6><div id=\"target-id6a56d05b33031\" class=\"collapseomatic_content \">\n\n\n\n<p><strong>D\u00eda\n01 (Lunes) Berl\u00edn<\/strong><\/p>\n\n\n\n<p><strong><em>Llegamos a Europa <\/em><\/strong><\/p>\n\n\n\n<p>Llegada&nbsp; al aeropuerto y <strong>traslado<\/strong> al hotel<strong>.&nbsp; &nbsp;&nbsp;Alojamiento. <\/strong>A las 19.30&nbsp;\nhrs, tendr\u00e1 lugar la reuni\u00f3n con el gu\u00eda en la recepci\u00f3n del hotel donde\nconoceremos&nbsp; al resto de participantes.<\/p>\n\n\n\n<p><strong>D\u00eda\n02 (Martes) Berl\u00edn.<\/strong><\/p>\n\n\n\n<p><strong><em>&#8230;Capital liberada y\nlibre<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno y visita panor\u00e1mica<\/strong> con&nbsp; la Puerta\nde Brandemburgo,&nbsp; el Reichstag; la Unter\nden Linten, Iglesia conmemorativa del K\u00e1iser en la Ku\u00b4Damm,&nbsp; Alexander Platz,&nbsp; East&nbsp;\nSide Gallery, memorial al Muro de Berl\u00edn. Posibilidad de visitar\nopcionalmente alguno de los Museos de Berl\u00edn y el Campo de Concentraci\u00f3n de\nSchasenhausen.&nbsp; <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p>ERIAL24 D\u00cdAS \/ 9 PA\u00cdSES)<\/p>\n\n\n\n<p><strong>D\u00eda 03\n(Mi\u00e9rcoles) Berl\u00edn \u2013 Poznan \u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>.. Por fin \u2026 Polonia <\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno.\n<\/strong>Salida con direcci\u00f3n <strong>Poznan<\/strong>. Llegada y\ntour de orientaci\u00f3n de una de las mas antiguas y grandes ciudades de Polonia.\nEl centro tur\u00edstico de la ciudad es la Antigua Plaza del Mercado con valiosos\nmonumentos y numerosos museos. El ayuntamiento renacentista, con bellas\ngaler\u00edas abiertas, alberga el Museo de Historia de la Ciudad, etc. Continuaci\u00f3n\ndel viaje hasta Varsovia. &nbsp;<strong>&nbsp;<\/strong>&nbsp;<strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 04 (Jueves)\n\u2013 Varsovia<\/strong><\/p>\n\n\n\n<p><strong><em>La gran capital<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno.\nVisita panor\u00e1mica <\/strong>de la ciudad que nos mostrar\u00e1 los\nprincipales monumentos y cualidades de s\u00ed misma, especialmente aquellos\nsituados alrededor de la ruta real, ayuntamiento y los distintos homenajes a\nsucesos recientes de la segunda guerra mundial como el gueto jud\u00edo.Tarde\nlibre para realizar algunavisita facultativa: Castillo Real o Palacio\nWilanow.<\/p>\n\n\n\n<p><strong>D\u00eda 05 (Viernes)\n\u2013 Varsovia \u2013 Czestochowa \u2013 Cracovia<\/strong><\/p>\n\n\n\n<p><strong><em>Santuarios y tradiciones<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno<\/strong>.\nSalimos al encuentro de la Virgen Morena de todos los polacos. Su santuario nos\nsobrecoger\u00e1 por su iluminaci\u00f3n y estructura. Son millones los visitantes que\ndurante siglo ha atra\u00eddo esta Virgen. La devoci\u00f3n mariana es la reina en <strong>Czestochowa<\/strong>.\nContinuaremos hacia Cracovia . El castillo de Cracovia, las iglesias\nmedievales, la ciudad vieja, son algunos de los monumentos que nos impresionar\u00e1n.\nLa Lonja hist\u00f3rica, a\u00fan mercadillo tradicional, el gueto jud\u00edo y las calles de\nlos palacios barrocos ser\u00e1n otras de las gemas que se nos mostrar\u00e1n en la <strong>visita\npanor\u00e1mica <\/strong>de la ciudad. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda 06 (S\u00e1bado)\nCracovia<\/strong><\/p>\n\n\n\n<p><strong><em>La Catedral de Sal<\/em><\/strong><em><\/em><\/p>\n\n\n\n<p><strong>Desayuno. <\/strong>D\u00eda libre para\nvisitar opcionalmente el Campo de Concentraci\u00f3n de\nAuschwith y las Minas de sal de Wielivska. <strong>Alojamiento<\/strong>.<\/p>\n\n\n\n<p><strong>D\u00eda\n07 (Domingo) Cracovia &nbsp;&#8211; ciudad de origen&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n\n\n\n<p><strong><em>Vuelta a casa<\/em><\/strong><\/p>\n\n\n\n<p><strong>Desayuno<\/strong> y tiempo libre hasta la hora del <strong>traslado<\/strong> al aeropuerto. Fin de nuestros servicios.<\/p>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"text-align:center\"><strong>PDF<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.surland.com\/uploads\/es\/142-045257.pdf\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=47%2C47&#038;ssl=1\" alt=\"\" class=\"wp-image-538\" width=\"47\" height=\"47\" srcset=\"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/pdf.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 47px) 100vw, 47px\" \/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rutas por Polonia - Maratones y viajes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rutas por Polonia - Maratones y viajes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Maratones y viajes\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-01T20:59:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-01T20:59:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/#\\\/schema\\\/person\\\/db718ca08ea7ee8388b784a6613ed518\"},\"headline\":\"Rutas por Polonia\",\"datePublished\":\"2019-07-01T20:59:29+00:00\",\"dateModified\":\"2019-07-01T20:59:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/\"},\"wordCount\":3524,\"image\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/maratonesyviajes.com\\\/viajes\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/polonia.jpg?fit=768%2C512&ssl=1\",\"articleSection\":[\"Europa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/\",\"url\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/\",\"name\":\"Rutas por Polonia - Maratones y viajes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/maratonesyviajes.com\\\/viajes\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/polonia.jpg?fit=768%2C512&ssl=1\",\"datePublished\":\"2019-07-01T20:59:29+00:00\",\"dateModified\":\"2019-07-01T20:59:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/#\\\/schema\\\/person\\\/db718ca08ea7ee8388b784a6613ed518\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/maratonesyviajes.com\\\/viajes\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/polonia.jpg?fit=768%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/maratonesyviajes.com\\\/viajes\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/polonia.jpg?fit=768%2C512&ssl=1\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/rutas-por-polonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rutas por Polonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/#website\",\"url\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/\",\"name\":\"Maratones y viajes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/#\\\/schema\\\/person\\\/db718ca08ea7ee8388b784a6613ed518\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bd69694e891bf1521c9f6b1167195c70d772e31c978744f6eadafc2e2414639?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bd69694e891bf1521c9f6b1167195c70d772e31c978744f6eadafc2e2414639?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bd69694e891bf1521c9f6b1167195c70d772e31c978744f6eadafc2e2414639?s=96&d=mm&r=g\",\"caption\":\"user\"},\"url\":\"https:\\\/\\\/maratonesyviajes.com\\\/viajes\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rutas por Polonia - Maratones y viajes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/","og_locale":"es_MX","og_type":"article","og_title":"Rutas por Polonia - Maratones y viajes","og_url":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/","og_site_name":"Maratones y viajes","article_published_time":"2019-07-01T20:59:29+00:00","article_modified_time":"2019-07-01T20:59:31+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/i2.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#article","isPartOf":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/"},"author":{"name":"user","@id":"https:\/\/maratonesyviajes.com\/viajes\/#\/schema\/person\/db718ca08ea7ee8388b784a6613ed518"},"headline":"Rutas por Polonia","datePublished":"2019-07-01T20:59:29+00:00","dateModified":"2019-07-01T20:59:31+00:00","mainEntityOfPage":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/"},"wordCount":3524,"image":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1","articleSection":["Europa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/","url":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/","name":"Rutas por Polonia - Maratones y viajes","isPartOf":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#primaryimage"},"image":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1","datePublished":"2019-07-01T20:59:29+00:00","dateModified":"2019-07-01T20:59:31+00:00","author":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/#\/schema\/person\/db718ca08ea7ee8388b784a6613ed518"},"breadcrumb":{"@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#primaryimage","url":"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/maratonesyviajes.com\/viajes\/rutas-por-polonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/maratonesyviajes.com\/viajes\/"},{"@type":"ListItem","position":2,"name":"Rutas por Polonia"}]},{"@type":"WebSite","@id":"https:\/\/maratonesyviajes.com\/viajes\/#website","url":"https:\/\/maratonesyviajes.com\/viajes\/","name":"Maratones y viajes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maratonesyviajes.com\/viajes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/maratonesyviajes.com\/viajes\/#\/schema\/person\/db718ca08ea7ee8388b784a6613ed518","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2bd69694e891bf1521c9f6b1167195c70d772e31c978744f6eadafc2e2414639?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bd69694e891bf1521c9f6b1167195c70d772e31c978744f6eadafc2e2414639?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bd69694e891bf1521c9f6b1167195c70d772e31c978744f6eadafc2e2414639?s=96&d=mm&r=g","caption":"user"},"url":"https:\/\/maratonesyviajes.com\/viajes\/author\/user\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/maratonesyviajes.com\/viajes\/wp-content\/uploads\/2019\/06\/polonia.jpg?fit=768%2C512&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/posts\/717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/comments?post=717"}],"version-history":[{"count":1,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/posts\/717\/revisions"}],"predecessor-version":[{"id":718,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/posts\/717\/revisions\/718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/media\/642"}],"wp:attachment":[{"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/media?parent=717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/categories?post=717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maratonesyviajes.com\/viajes\/wp-json\/wp\/v2\/tags?post=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}